{"id":5849,"date":"2023-12-11T21:53:58","date_gmt":"2023-12-11T21:53:58","guid":{"rendered":"https:\/\/tlcmagazinemexico.com.mx\/?p=5849"},"modified":"2023-12-12T19:50:01","modified_gmt":"2023-12-12T19:50:01","slug":"baja-ferries-nombra-a-nino-liano-egozcue-como-nuevo-director-general","status":"publish","type":"post","link":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2023\/12\/11\/baja-ferries-nombra-a-nino-liano-egozcue-como-nuevo-director-general\/","title":{"rendered":"Baja Ferries nombra a Nino Lia\u00f1o Egozcue como nuevo Director General"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5849\" class=\"elementor elementor-5849\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5231c837 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5231c837\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-635f67a2\" data-id=\"635f67a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38438e24 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"38438e24\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.0 - 29-03-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/12\/45g-1-3.png\" class=\"attachment-large size-large wp-image-5851\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/12\/45g-1-3.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/12\/45g-1-3-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/12\/45g-1-3-768x512.png 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" style=\"width:100%;height:66.67%;max-width:900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e71b4d2 elementor-widget elementor-widget-spacer\" data-id=\"4e71b4d2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.0 - 29-03-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50891704 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"50891704\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.0 - 29-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Baja Ferries nombra a Nino Lia\u00f1o Egozcue como nuevo Director General<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7eec2631 elementor-widget elementor-widget-text-editor\" data-id=\"7eec2631\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.0 - 29-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><!-- wp:paragraph --><\/p>\n<p>Nino Lia\u00f1o, actual CFO de Baja Ferries, asumir\u00e1 la Direcci\u00f3n General a partir del 1 de enero 2024.<\/p>\n<p><br>Tras seis a\u00f1os al mando y con extraordinarios resultados, Ariel Pozo deja el grupo.<br>La labor conjunta entre ambos directivos ha sido esencial para cumplir la misi\u00f3n de Baja Ferries:<\/p>\n<p><br><b>Uniendo territorios, conectando personas.<\/b><\/p>\n<p>04 de diciembre de 2023, La Paz, Baja California Sur. Baja Ferries, el grupo log\u00edstico &#8211; naviero, especializado en transbordadores de carga y pasaje, da a conocer el cambio en la Direcci\u00f3n General de la empresa.<\/p>\n<p><br>Tras un ciclo de seis a\u00f1os de gesti\u00f3n en los que se cumpli\u00f3 la encomienda del Consejo de Administraci\u00f3n de institucionalizar el Gobierno Corporativo, Ariel Pozo concluye su ciclo dentro de Baja Ferries.<\/p>\n<p><br>&#8220;Durante los \u00faltimos seis a\u00f1os, en Baja Ferries hemos trascendido metas, superado expectativas y construido juntos un legado de \u00e9xito. Los objetivos por los que llegu\u00e9 a la empresa se han cumplido. Por ello hoy concluyo mi ciclo como Director General, agradecido por cada logro compartido. A su vez, tengo el honor de anunciar una nueva etapa para la empresa, donde estoy seguro de que el equipo continuar\u00e1 elevando est\u00e1ndares y alcanzando nuevas alturas. Conf\u00edo en haber trazado el rumbo y cada uno de los integrantes seguir\u00e1 contribuyendo al brillante camino de Baja Ferries. \u00a1Gracias por estos inolvidables seis a\u00f1os juntos!&#8221;, se\u00f1al\u00f3 Ariel Pozo, Director General saliente.<\/p>\n<p><br>Entre los logros m\u00e1s destacados de Ariel Pozo se encuentran, el redise\u00f1o de la estructura administrativa, la implementaci\u00f3n de mejores pr\u00e1cticas de gobierno corporativo, la incorporaci\u00f3n de Baja Ferries entre las 100 Mejores Empresas Mexicanas y el posicionamiento de la empresa como el mayor referente en<br>actividades de responsabilidad social dentro del sector.<\/p>\n<p><br><b>Durante su gesti\u00f3n sucedieron hitos importantes para la compa\u00f1\u00eda como:<\/b><\/p>\n<p><br>La adquisici\u00f3n de los buques M\u00e9xico Star, Chiapas Star y California Star.<br>La Certificaci\u00f3n PRIME, por la implementaci\u00f3n de planes estrat\u00e9gicos que cumplen con altos est\u00e1ndares corporativos en apego a los requerimientos del mercado de valores.<\/p>\n<p><br>Afrontar la pandemia con una estructurada estrategia de resiliencia continua entre los a\u00f1os 2020 y 2022.<\/p>\n<p>Construcci\u00f3n de cimientos s\u00f3lidos que posicionan a la compa\u00f1\u00eda para continuar el camino de crecimiento.<\/p>\n<p><br><\/p>\n<p>Baja Ferries hace un merecido reconocimiento a la gesti\u00f3n y liderazgo de Ariel Pozo por estos a\u00f1os de servicio, quien seguir\u00e1 al frente de la firma hasta el \u00faltimo d\u00eda del a\u00f1o 2023.<\/p>\n<p><br>A partir del pr\u00f3ximo 1 de enero de 2024, Nino Lia\u00f1o, anteriormente CFO de la compa\u00f1\u00eda, asumir\u00e1 la Direcci\u00f3n General.<\/p>\n<p><br>Nino Lia\u00f1o Egozcue es un destacado estratega y financiero. En los \u00faltimos 5 a\u00f1os ha trabajado como CFO en Baja Ferries y cuenta con una larga trayectoria en empresas como AT&amp;T, Nextel y McDonald\u2019s.<\/p>\n<p><br>Cuenta con una maestr\u00eda en Alta Direcci\u00f3n por la Universidad An\u00e1huac y ha sido un ejecutivo clave en asegurar el crecimiento y la rentabilidad de las empresas y toda su cadena de Valor.<\/p>\n<p><br>&#8220;Asumo la responsabilidad de liderar Baja Ferries en esta nueva etapa. Heredamos un legado de m\u00e1s de 20 a\u00f1os de solidez y \u00e9xito; cimientos firmes construidos con dedicaci\u00f3n y visi\u00f3n de unir territorios y conectar personas. Gracias a ese respaldo, podemos mirar hacia adelante para impulsar a la empresa hacia nuevos proyectos y planes de crecimiento. Juntos, escribiremos el pr\u00f3ximo cap\u00edtulo de nuestra historia, confiados en la fortaleza de nuestro legado y en la determinaci\u00f3n de alcanzar horizontes a\u00fan m\u00e1s elevados. Estoy muy agradecido con el Consejo por la oportunidad de liderar este extraordinario equipo. \u00a1Estoy seguro que Baja Ferries tiene un futuro brillante que construiremos juntos!&#8221;, dijo Nino Lia\u00f1o, Director General entrante.<\/p>\n<p><br>De esta Forma Baja Ferries muestra que a lo largo de su historia ha contado y cuenta con personas clave que han permitido el desarrollo de la organizaci\u00f3n, siempre enfocada en ser un actor relevante dentro del sector mar\u00edtimo de M\u00e9xico, contribuyendo al desarrollo social y econ\u00f3mico del pa\u00eds y con un sentido de responsabilidad social, que garantizan el futuro de la empresa.<\/p><p><br><\/p><p>Visita el Sitio:&nbsp;https:\/\/www.bajaferries.com.mx\/<\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60e4d95 elementor-widget elementor-widget-image\" data-id=\"60e4d95\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/12\/Nino-Liano-1024x683.jpeg\" class=\"attachment-large size-large wp-image-5860\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/12\/Nino-Liano-1024x683.jpeg 1024w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/12\/Nino-Liano-300x200.jpeg 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/12\/Nino-Liano-768x512.jpeg 768w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/12\/Nino-Liano.jpeg 1500w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" style=\"width:100%;height:66.67%;max-width:1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b9b6ce5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9b6ce5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-25baca22\" data-id=\"25baca22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36a2085b elementor-widget elementor-widget-heading\" data-id=\"36a2085b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Compartir <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4907f611\" data-id=\"4907f611\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-508ce15b elementor-share-buttons--view-icon elementor-share-buttons--skin-flat elementor-share-buttons--align-right elementor-share-buttons--color-custom elementor-share-buttons-mobile--align-center elementor-share-buttons--shape-square elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"508ce15b\" data-element_type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-share-buttons.min.css\">\t\t<div class=\"elementor-grid\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_facebook\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en facebook\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_linkedin\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en linkedin\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_twitter\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en twitter\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_email\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en email\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d33b07e elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"2d33b07e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-73299857\" data-id=\"73299857\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ad70b93 elementor-widget elementor-widget-heading\" data-id=\"1ad70b93\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recibe las noticias m\u00e1s relevantes del medio<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-117c9aaa elementor-widget elementor-widget-heading\" data-id=\"117c9aaa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">en tu correo electr\u00f3nico<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10ba4b4e elementor-widget elementor-widget-spacer\" data-id=\"10ba4b4e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5099bf1d elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"5099bf1d\" data-element_type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;25&quot;,&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.12.0 - 29-03-2023 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"TLC News\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"5849\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"5099bf1d\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-75 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Correo electr\u00f3nico\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-25 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-md\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-align-icon-right elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-113ab266 elementor-post-navigation-borders-yes elementor-widget elementor-widget-post-navigation\" data-id=\"113ab266\" data-element_type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-theme-elements.min.css\">\t\t<div class=\"elementor-post-navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2023\/12\/11\/trabajadores-turisticos-afectados-por-otis-en-mexico-buscan-rescatar-ganancias-decembrinas\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i class=\"fa fa-arrow-left\" aria-hidden=\"true\"><\/i><span class=\"elementor-screen-only\">Previo<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Anterior<\/span><span class=\"post-navigation__prev--title\">Trabajadores tur\u00edsticos afectados por Otis en M\u00e9xico buscan rescatar ganancias decembrinas<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation__separator-wrapper\">\n\t\t\t\t\t<div class=\"elementor-post-navigation__separator\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2023\/12\/13\/reduccion-de-la-jornada-laboral-en-mexico-se-mantiene-en-suspenso-en-el-congreso\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">siguiente<\/span><span class=\"post-navigation__next--title\">Reducci\u00f3n de la jornada laboral en M\u00e9xico se mantiene en suspenso en el Congreso<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i class=\"fa fa-arrow-right\" aria-hidden=\"true\"><\/i><span class=\"elementor-screen-only\">Next<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-73d0609e\" data-id=\"73d0609e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-403171d4\" data-id=\"403171d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-765b855e elementor-grid-1 elementor-posts--align-center elementor-posts__hover-none elementor-widget__width-inherit elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-widget elementor-widget-posts\" data-id=\"765b855e\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;30&quot;,&quot;sizes&quot;:[]},&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24329 post type-post status-publish format-standard has-post-thumbnail hentry category-global-customs-tech category-ia-aplicada-a-comercio-exterior category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/inteligencia-artificial-agentica-entra-a-la-agenda-global-de-las-aduanas-con-respaldo-de-la-oma\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n1-2.png\" class=\"attachment-full size-full wp-image-24330\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n1-2.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n1-2-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n1-2-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/inteligencia-artificial-agentica-entra-a-la-agenda-global-de-las-aduanas-con-respaldo-de-la-oma\/\" >\n\t\t\t\tInteligencia artificial ag\u00e9ntica entra a la agenda global de las aduanas con respaldo de la OMA\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u2022 La WCO News Magazine public\u00f3 el primer an\u00e1lisis sobre IA ag\u00e9ntica aplicada a administraciones aduaneras, una tecnolog\u00eda que promete reducir de meses a minutos<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/inteligencia-artificial-agentica-entra-a-la-agenda-global-de-las-aduanas-con-respaldo-de-la-oma\/\" aria-label=\"Read more about Inteligencia artificial ag\u00e9ntica entra a la agenda global de las aduanas con respaldo de la OMA\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24354 post type-post status-publish format-standard has-post-thumbnail hentry category-indicadores-globales category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/importaciones-de-contenedores-en-ee-uu-apuntan-a-record-historico-por-adelanto-ante-presion-arancelaria\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n5-1.png\" class=\"attachment-full size-full wp-image-24355\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n5-1.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n5-1-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n5-1-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/importaciones-de-contenedores-en-ee-uu-apuntan-a-record-historico-por-adelanto-ante-presion-arancelaria\/\" >\n\t\t\t\tImportaciones de contenedores en EE.UU. apuntan a r\u00e9cord hist\u00f3rico por adelanto ante presi\u00f3n arancelaria\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u2022 Los puertos estadounidenses esperan 2.47 millones de TEU en julio de 2026, impulsados por el adelanto de compras antes del vencimiento de medidas arancelarias.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/importaciones-de-contenedores-en-ee-uu-apuntan-a-record-historico-por-adelanto-ante-presion-arancelaria\/\" aria-label=\"Read more about Importaciones de contenedores en EE.UU. apuntan a r\u00e9cord hist\u00f3rico por adelanto ante presi\u00f3n arancelaria\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24349 post type-post status-publish format-standard has-post-thumbnail hentry category-best-practices-de-aduanas-y-puertos category-rutas-y-corredores category-sostenibilidad category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/restricciones-de-agosto-en-el-canal-de-panama-podrian-presionar-rutas-transpacificas\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n4-1.png\" class=\"attachment-full size-full wp-image-24333\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n4-1.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n4-1-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n4-1-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/restricciones-de-agosto-en-el-canal-de-panama-podrian-presionar-rutas-transpacificas\/\" >\n\t\t\t\tRestricciones de agosto en el Canal de Panam\u00e1 podr\u00edan presionar rutas transpac\u00edficas\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u2022 La reducci\u00f3n de calado en esclusas Neopanamax, junto con salidas en blanco y ajustes entre navieras, anticipa menor capacidad efectiva en corredores Asia\u2013Costa Este<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/restricciones-de-agosto-en-el-canal-de-panama-podrian-presionar-rutas-transpacificas\/\" aria-label=\"Read more about Restricciones de agosto en el Canal de Panam\u00e1 podr\u00edan presionar rutas transpac\u00edficas\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24344 post type-post status-publish format-standard has-post-thumbnail hentry category-best-practices-de-aduanas-y-puertos category-datos-curiosos category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/yangshan-y-singapur-lideran-rankings-portuarios-globales-bajo-metricas-distintas\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n3-1.png\" class=\"attachment-full size-full wp-image-24332\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n3-1.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n3-1-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n3-1-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/yangshan-y-singapur-lideran-rankings-portuarios-globales-bajo-metricas-distintas\/\" >\n\t\t\t\tYangshan y Singapur lideran rankings portuarios globales bajo m\u00e9tricas distintas\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u2022 El CPPI del Banco Mundial mide eficiencia operativa por tiempo de permanencia de buques, mientras el ranking de DNV y Menon Economics eval\u00faa competitividad<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/yangshan-y-singapur-lideran-rankings-portuarios-globales-bajo-metricas-distintas\/\" aria-label=\"Read more about Yangshan y Singapur lideran rankings portuarios globales bajo m\u00e9tricas distintas\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24338 post type-post status-publish format-standard has-post-thumbnail hentry category-global-customs-tech category-robots-en-la-cadena-logistica category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/ambi-robotics-y-pickle-robot-integran-solucion-robotica-para-automatizar-la-logistica-entrante\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n2-1.png\" class=\"attachment-full size-full wp-image-24331\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n2-1.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n2-1-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n2-1-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/ambi-robotics-y-pickle-robot-integran-solucion-robotica-para-automatizar-la-logistica-entrante\/\" >\n\t\t\t\tAmbi Robotics y Pickle Robot integran soluci\u00f3n rob\u00f3tica para automatizar la log\u00edstica entrante\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u2022 La alianza combina descarga automatizada de tr\u00e1ileres, escaneo, identificaci\u00f3n y paletizaci\u00f3n de paquetes en centros de distribuci\u00f3n. \u00a0 Ambi Robotics y Pickle Robot Company<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/ambi-robotics-y-pickle-robot-integran-solucion-robotica-para-automatizar-la-logistica-entrante\/\" aria-label=\"Read more about Ambi Robotics y Pickle Robot integran soluci\u00f3n rob\u00f3tica para automatizar la log\u00edstica entrante\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24121 post type-post status-publish format-standard has-post-thumbnail hentry category-oportunidades-de-negocio category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/13\/mexico-ampliara-sus-exportaciones-de-azucar-a-eeuu-tras-un-aumento-del-512-en-la-demanda\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n8.png\" class=\"attachment-full size-full wp-image-24122\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n8.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n8-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n8-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/13\/mexico-ampliara-sus-exportaciones-de-azucar-a-eeuu-tras-un-aumento-del-512-en-la-demanda\/\" >\n\t\t\t\tM\u00e9xico ampliar\u00e1 sus exportaciones de az\u00facar a EEUU tras un aumento del 512 % en la demanda\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>M\u00e9xico aumentar\u00e1 sus exportaciones de az\u00facar a Estados Unidos durante el pr\u00f3ximo ciclo comercial, luego de que el Departamento de Agricultura de Estados Unidos (USDA)<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/13\/mexico-ampliara-sus-exportaciones-de-azucar-a-eeuu-tras-un-aumento-del-512-en-la-demanda\/\" aria-label=\"Read more about M\u00e9xico ampliar\u00e1 sus exportaciones de az\u00facar a EEUU tras un aumento del 512 % en la demanda\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nino Lia\u00f1o, actual CFO de Baja Ferries, asumir\u00e1 la Direcci\u00f3n General a partir del 1 de enero 2024. Tras seis a\u00f1os al mando y con extraordinarios resultados, Ariel Pozo deja el grupo.La labor conjunta entre ambos directivos ha sido esencial para cumplir la misi\u00f3n de Baja Ferries: Uniendo territorios, conectando personas. 04 de diciembre de&hellip; <a class=\"more-link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/13\/mexico-ampliara-sus-exportaciones-de-azucar-a-eeuu-tras-un-aumento-del-512-en-la-demanda\/\">Seguir leyendo <span class=\"screen-reader-text\">M\u00e9xico ampliar\u00e1 sus exportaciones de az\u00facar a EEUU tras un aumento del 512 % en la demanda<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":5851,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-5849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tlc-news","entry"],"views":1643,"_links":{"self":[{"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5849"}],"version-history":[{"count":10,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5849\/revisions"}],"predecessor-version":[{"id":5863,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5849\/revisions\/5863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5851"}],"wp:attachment":[{"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}