{"id":3386,"date":"2023-08-04T19:19:48","date_gmt":"2023-08-04T19:19:48","guid":{"rendered":"https:\/\/tlcmagazinemexico.com.mx\/?p=3386"},"modified":"2023-08-04T20:09:58","modified_gmt":"2023-08-04T20:09:58","slug":"informes-sobre-la-situacion-economica-las-finanzas-publicas-y-la-deuda-publica-al-segundo-trimestre-de-2023","status":"publish","type":"post","link":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2023\/08\/04\/informes-sobre-la-situacion-economica-las-finanzas-publicas-y-la-deuda-publica-al-segundo-trimestre-de-2023\/","title":{"rendered":"Informes sobre la Situaci\u00f3n Econ\u00f3mica, las Finanzas P\u00fablicas y la Deuda P\u00fablica al segundo trimestre de 2023"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3386\" class=\"elementor elementor-3386\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fa11732 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fa11732\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1b7ddde2\" data-id=\"1b7ddde2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-154faad1 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"154faad1\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.0 - 29-03-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/07\/31g.png\" class=\"attachment-large size-large wp-image-3038\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/07\/31g.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/07\/31g-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2023\/07\/31g-768x512.png 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" style=\"width:100%;height:66.67%;max-width:900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f5f7471 elementor-widget elementor-widget-spacer\" data-id=\"1f5f7471\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.0 - 29-03-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d25f0b9 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"1d25f0b9\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.0 - 29-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Informes sobre la Situaci\u00f3n Econ\u00f3mica, las Finanzas P\u00fablicas y la Deuda P\u00fablica al segundo trimestre de 2023<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ec51b45 elementor-widget elementor-widget-text-editor\" data-id=\"5ec51b45\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.0 - 29-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><!-- wp:paragraph --><\/p>\n<p>La econom\u00eda mexicana continu\u00f3 creciendo con equilibrios macroecon\u00f3micos s\u00f3lidos y, como ya se anticipaba, desde el Paquete Econ\u00f3mico, se prev\u00e9 que el PIB alcance el 3.0% en 2023.<\/p><p><br>Esto ha sido posible gracias a las reformas implementadas por esta administraci\u00f3n, que han permitido alcanzar m\u00e1ximos hist\u00f3ricos en los niveles de empleo y en el poder adquisitivo de los trabajadores.<\/p><p><br>En la primera mitad del a\u00f1o, la recaudaci\u00f3n tributaria registr\u00f3 el incremento m\u00e1s alto desde 2019, al aumentar 4.1% real anual.<\/p><p><br>Los balances de finanzas p\u00fablicas se encuentran en l\u00ednea con el programa para el cierre de 2023, lo que garantiza que la deuda p\u00fablica con respecto al PIB se mantenga en un nivel sostenible.<\/p><p><br><\/p>\n<p>En el segundo trimestre de 2023, la econom\u00eda global mostr\u00f3 signos de fortaleza por el buen desempe\u00f1o de los sectores de servicios y la s\u00f3lida creaci\u00f3n de empleo en econom\u00edas avanzadas, en un escenario marcado por altas tasas de inter\u00e9s y los conflictos geopol\u00edticos.<\/p><p><br>Las presiones inflacionarias a nivel global continuaron descendiendo, apoyadas en el restablecimiento de las cadenas de valor y la disminuci\u00f3n en los precios de los energ\u00e9ticos y las materias primas. No obstante, los niveles de inflaci\u00f3n general se mantuvieron por encima de los objetivos de los bancos centrales.<\/p><p><br>Solidez de la econom\u00eda mexicana<\/p>\n<p>Durante los meses de abril y mayo, el Indicador Global de la Actividad Econ\u00f3mica (IGAE) aument\u00f3 0.8% en comparaci\u00f3n con el bimestre anterior, con lo que acumul\u00f3 diez bimestres de crecimiento continuo. Adem\u00e1s, en el bimestre se observaron incrementos en todos sus componentes.<\/p><p><br>La demanda interna se mantuvo como el principal motor de la econom\u00eda mexicana. S\u00f3lo en abril, el consumo privado aument\u00f3 0.5%, tres veces por encima de su promedio hist\u00f3rico de 2011 a 2019.<\/p><p><br>La inversi\u00f3n privada tambi\u00e9n mostr\u00f3 se\u00f1ales positivas, con un aumento de 3.3% durante el primer trimestre, con lo que alcanz\u00f3 su mayor contribuci\u00f3n al crecimiento anual de la demanda agregada desde 2012. Destac\u00f3 que no se hab\u00eda observado un crecimiento sostenido de la inversi\u00f3n privada similar a este, incluso despu\u00e9s de las crisis de 1994 y 2009.<\/p><p><br>La inflaci\u00f3n continu\u00f3 disminuyendo y, en la primera quincena de julio, se ubic\u00f3 en 4.8%, el nivel m\u00e1s bajo desde la primera quincena de marzo de 2021. Adem\u00e1s, la inflaci\u00f3n al productor mostr\u00f3 una ca\u00edda en 3.1 puntos porcentuales (pp) durante el segundo trimestre del a\u00f1o. Se espera que esta disminuci\u00f3n contin\u00fae estimulando a la baja las presiones en los precios al consumidor durante los siguientes meses.<\/p><p><br>Respecto al comercio exterior, durante el bimestre de abril y mayo de 2023, M\u00e9xico se posicion\u00f3 como el principal socio comercial de Estados Unidos. En particular, las exportaciones manufactureras a ese pa\u00eds ganaron participaci\u00f3n en 1.6 pp respecto al mismo periodo de 2022.<\/p><p><br>En el primer trimestre de 2023, se registr\u00f3 la mayor entrada neta de recursos desde 2017 a trav\u00e9s de la cuenta financiera, por concepto de la inversi\u00f3n extranjera directa, la repatriaci\u00f3n de capitales y el regreso de la inversi\u00f3n en cartera.<\/p><p><br>Estabilidad fiscal y fortaleza de la recaudaci\u00f3n tributaria<\/p>\n<p>Durante la primera mitad del a\u00f1o, las finanzas p\u00fablicas se mantuvieron sanas, con mejores resultados en los balances fiscales respecto a los programados. Los riesgos asociados con las altas tasas de inter\u00e9s se mantuvieron controlados, al tiempo que se vigil\u00f3 el efecto de la apreciaci\u00f3n del peso en la recaudaci\u00f3n y los ingresos petroleros.<\/p><p><br>La recaudaci\u00f3n tributaria aument\u00f3 4.1% anual real entre enero y junio, sumando seis a\u00f1os de crecimiento continuo para un primer semestre. Este resultado se debi\u00f3 principalmente al dinamismo del ISR y la recuperaci\u00f3n del IEPS de gasolinas y diesel, cuyo cobro sum\u00f3 83 mil 614.1 millones de pesos y se ubic\u00f3 en terreno positivo por octavo mes consecutivo.<\/p><p><br>Gracias al aumento de los salarios, la creaci\u00f3n de empleos y las ganancias de las empresas, la recaudaci\u00f3n del ISR mostr\u00f3 un crecimiento real anual de 2.9% en la primera mitad del a\u00f1o, ligando dos a\u00f1os de incrementos continuos. Este impuesto represent\u00f3 42.4% del crecimiento total de la recaudaci\u00f3n tributaria.<\/p><p><br>En l\u00ednea con el desempe\u00f1o del consumo, el IEPS distinto de combustibles ascendi\u00f3 a 108 mil 166.1 millones de pesos entre enero y junio, lo que represent\u00f3 un crecimiento real de 4.7% respecto al mismo periodo de 2022. As\u00ed, el IEPS total continu\u00f3 con su recuperaci\u00f3n, superando en 2.4 veces el nivel observado en el primer semestre de 2022, en t\u00e9rminos reales.<\/p><p><br>Aunque la recaudaci\u00f3n se mantuvo s\u00f3lida, los menores precios internacionales del crudo y el gas, junto con la apreciaci\u00f3n del peso respecto al d\u00f3lar estadounidense, tuvieron un efecto negativo en los ingresos petroleros. En el mismo sentido, la apreciaci\u00f3n de la moneda nacional tuvo un impacto desfavorable en la recaudaci\u00f3n del IVA.<\/p><p><br>Gesti\u00f3n efectiva del gasto p\u00fablico y cumplimiento de las metas fiscales<\/p>\n<p>En cuanto al gasto p\u00fablico, el 66.1% se asign\u00f3 a desarrollo social, 25.3% a desarrollo econ\u00f3mico, 8.1% a funciones del gobierno y 0.5% a fondos de estabilizaci\u00f3n.<br>El gasto en desarrollo social creci\u00f3 6.3% real respecto al primer semestre 2022, registrando seis a\u00f1os de crecimiento continuo para un primer semestre y la tasa m\u00e1s alta en lo que va de la administraci\u00f3n. Por su parte, la inversi\u00f3n f\u00edsica creci\u00f3 8.9% en comparaci\u00f3n con el mismo periodo de 2022, en apoyo al crecimiento de la actividad econ\u00f3mica.<\/p><p><br>Por otro lado, el gasto de operaci\u00f3n fue menor en 2.7% real respecto a lo observado en el primer semestre del a\u00f1o anterior, reiterando el compromiso establecido en el Plan Nacional de Desarrollo de implementar una pol\u00edtica de austeridad republicana.<\/p><p><br>El costo financiero no represent\u00f3 una presi\u00f3n para las finanzas p\u00fablicas. Incluso, las previsiones actuales apuntan a un mejor resultado que los estimados en el Paquete Econ\u00f3mico 2023 y los Pre-Criterios 2024. Esto, a pesar de que las tasas de inter\u00e9s a nivel internacional continuaron aumentando. Al cierre del primer semestre, aunque el costo financiero present\u00f3 un aumento de 34.0% en t\u00e9rminos reales respecto al primer semestre de 2022, \u00e9ste se ubic\u00f3 en l\u00ednea con el programa.<\/p><p><br>Los agregados fiscales mostraron resultados mejores que lo previsto. El balance presupuestario present\u00f3 un menor d\u00e9ficit al previsto en 90 mil 271.6 millones de pesos, mientras que el balance primario presupuestario mostr\u00f3 un mayor super\u00e1vit respecto al programado en 90 mil 903.8 millones de pesos. Finalmente, los RFSP ascendieron a 496 mil 860.2 millones de pesos.<\/p><p><br>Manejo prudente y responsable de la deuda p\u00fablica<\/p>\n<p>Al cierre de junio, la deuda neta del Gobierno Federal fue de 11 billones 919 mil 14.4 millones de pesos, manteniendo su portafolio s\u00f3lido, con una exposici\u00f3n de riesgo baja y controlada. El 83.3% de los pasivos se mantuvo como deuda interna, del cual, 76.3% fue contratado a tasa de inter\u00e9s fija y con vencimientos a largo plazo.<\/p><p><br>La deuda p\u00fablica continu\u00f3 con una trayectoria estable y sostenible, como resultado de una pol\u00edtica fiscal responsable. Al cierre de junio, el SHRFSP ascendi\u00f3 a 14 billones 60 mil 651.3 millones de pesos y, como porcentaje del PIB, se ubic\u00f3 en 45.8%.<\/p><p><br>Durante el segundo trimestre de 2023, como parte de una pol\u00edtica activa de refinanciamiento, la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico llev\u00f3 a cabo operaciones de deuda principalmente en el mercado interno, y de forma complementaria en el mercado externo, con el objetivo de mejorar el perfil de vencimientos, reducir presiones de liquidez y disminuir las amortizaciones de corto plazo.<\/p><p><br>Al primer semestre del a\u00f1o se han refinanciado 2 mil millones de d\u00f3lares de deuda externa y 478 mil millones de pesos de deuda interna. Durante toda la administraci\u00f3n se han refinanciado un total de 14.6 mil millones de d\u00f3lares y 1.7 billones de pesos de deuda externa y deuda interna, respectivamente.<\/p><p><br>Dentro de las operaciones realizadas en el mercado interno, destac\u00f3 la operaci\u00f3n de compra y venta de Bondes F por un monto de 36 mil millones de pesos, realizada el 28 de junio. Con esta operaci\u00f3n, se logr\u00f3 una reducci\u00f3n de 36 mil 271 millones de pesos en los pagos de la deuda interna programados para 2023 y 2024.<\/p><p><br>Estas operaciones reafirman el compromiso del Gobierno Federal con las finanzas sanas y s\u00f3lidas, al aprovechar las ventanas de oportunidad que permitan obtener las mejores condiciones financieras en el manejo de la deuda.<\/p><p><br>La estrategia de deuda p\u00fablica ha buscado ampliar la base de inversionistas al diversificar los mercados y fuentes de financiamiento, as\u00ed como al incluir emisiones basadas en el Marco de Referencia de los Bonos Soberanos vinculados a los ODS.<\/p><p><br>Reiteramos que todas las colocaciones de deuda se realizaron en el marco del Programa Anual de Financiamiento 2023, de acuerdo con la Ley Federal de Deuda P\u00fablica y en l\u00ednea con los techos de endeudamiento aprobados por el H. Congreso de la Uni\u00f3n para el ejercicio fiscal 2023.<\/p><p><br><\/p>\n<p>FUENTE: Gobierno de M\u00e9xico<br>https:\/\/efs.efeservicios.com\/noticia-multimedia\/opep-fuertes-recortes-oferta-crudo\/55011660280<\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4d1382ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d1382ed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-490043f\" data-id=\"490043f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22bad33d elementor-widget elementor-widget-heading\" data-id=\"22bad33d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Compartir <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3962faa\" data-id=\"3962faa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f8188b2 elementor-share-buttons--view-icon elementor-share-buttons--skin-flat elementor-share-buttons--align-right elementor-share-buttons--color-custom elementor-share-buttons-mobile--align-center elementor-share-buttons--shape-square elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"1f8188b2\" data-element_type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-share-buttons.min.css\">\t\t<div class=\"elementor-grid\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_facebook\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en facebook\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_linkedin\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en linkedin\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_twitter\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en twitter\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_email\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en email\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7b6f6740 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"7b6f6740\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-33d892d3\" data-id=\"33d892d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4417ad9f elementor-widget elementor-widget-heading\" data-id=\"4417ad9f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recibe las noticias m\u00e1s relevantes del medio<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4b930 elementor-widget elementor-widget-heading\" data-id=\"ae4b930\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">en tu correo electr\u00f3nico<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36b24e9 elementor-widget elementor-widget-spacer\" data-id=\"36b24e9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f7c022e elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"1f7c022e\" data-element_type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;25&quot;,&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.12.0 - 29-03-2023 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"TLC News\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"3386\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"1f7c022e\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-75 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Correo electr\u00f3nico\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-25 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-md\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-align-icon-right elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cd658cd elementor-post-navigation-borders-yes elementor-widget elementor-widget-post-navigation\" data-id=\"1cd658cd\" data-element_type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-theme-elements.min.css\">\t\t<div class=\"elementor-post-navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2023\/08\/04\/participa-mexico-en-la-reunion-ministerial-de-seguridad-alimentaria-del-mecanismo-de-cooperacion-economica-asia-pacifico-apec\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i class=\"fa fa-arrow-left\" aria-hidden=\"true\"><\/i><span class=\"elementor-screen-only\">Previo<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Anterior<\/span><span class=\"post-navigation__prev--title\">Participa M\u00e9xico en la Reuni\u00f3n Ministerial de Seguridad Alimentaria del Mecanismo de Cooperaci\u00f3n Econ\u00f3mica Asia Pac\u00edfico (APEC)<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation__separator-wrapper\">\n\t\t\t\t\t<div class=\"elementor-post-navigation__separator\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2023\/08\/04\/la-opep-sigue-adelante-con-los-fuertes-recortes-de-su-oferta-de-crudo\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">siguiente<\/span><span class=\"post-navigation__next--title\">La OPEP+ sigue adelante con los fuertes recortes de su oferta de crudo<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i class=\"fa fa-arrow-right\" aria-hidden=\"true\"><\/i><span class=\"elementor-screen-only\">Next<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1fd38b77\" data-id=\"1fd38b77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5c17788a\" data-id=\"5c17788a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5994aaac elementor-grid-1 elementor-posts--align-center elementor-posts__hover-none elementor-widget__width-inherit elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-widget elementor-widget-posts\" data-id=\"5994aaac\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;30&quot;,&quot;sizes&quot;:[]},&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24329 post type-post status-publish format-standard has-post-thumbnail hentry category-global-customs-tech category-ia-aplicada-a-comercio-exterior category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/inteligencia-artificial-agentica-entra-a-la-agenda-global-de-las-aduanas-con-respaldo-de-la-oma\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n1-2.png\" class=\"attachment-full size-full wp-image-24330\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n1-2.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n1-2-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n1-2-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/inteligencia-artificial-agentica-entra-a-la-agenda-global-de-las-aduanas-con-respaldo-de-la-oma\/\" >\n\t\t\t\tInteligencia artificial ag\u00e9ntica entra a la agenda global de las aduanas con respaldo de la OMA\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u2022 La WCO News Magazine public\u00f3 el primer an\u00e1lisis sobre IA ag\u00e9ntica aplicada a administraciones aduaneras, una tecnolog\u00eda que promete reducir de meses a minutos<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/inteligencia-artificial-agentica-entra-a-la-agenda-global-de-las-aduanas-con-respaldo-de-la-oma\/\" aria-label=\"Read more about Inteligencia artificial ag\u00e9ntica entra a la agenda global de las aduanas con respaldo de la OMA\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24354 post type-post status-publish format-standard has-post-thumbnail hentry category-indicadores-globales category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/importaciones-de-contenedores-en-ee-uu-apuntan-a-record-historico-por-adelanto-ante-presion-arancelaria\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n5-1.png\" class=\"attachment-full size-full wp-image-24355\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n5-1.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n5-1-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n5-1-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/importaciones-de-contenedores-en-ee-uu-apuntan-a-record-historico-por-adelanto-ante-presion-arancelaria\/\" >\n\t\t\t\tImportaciones de contenedores en EE.UU. apuntan a r\u00e9cord hist\u00f3rico por adelanto ante presi\u00f3n arancelaria\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u2022 Los puertos estadounidenses esperan 2.47 millones de TEU en julio de 2026, impulsados por el adelanto de compras antes del vencimiento de medidas arancelarias.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/importaciones-de-contenedores-en-ee-uu-apuntan-a-record-historico-por-adelanto-ante-presion-arancelaria\/\" aria-label=\"Read more about Importaciones de contenedores en EE.UU. apuntan a r\u00e9cord hist\u00f3rico por adelanto ante presi\u00f3n arancelaria\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24349 post type-post status-publish format-standard has-post-thumbnail hentry category-best-practices-de-aduanas-y-puertos category-rutas-y-corredores category-sostenibilidad category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/restricciones-de-agosto-en-el-canal-de-panama-podrian-presionar-rutas-transpacificas\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n4-1.png\" class=\"attachment-full size-full wp-image-24333\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n4-1.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n4-1-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n4-1-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/restricciones-de-agosto-en-el-canal-de-panama-podrian-presionar-rutas-transpacificas\/\" >\n\t\t\t\tRestricciones de agosto en el Canal de Panam\u00e1 podr\u00edan presionar rutas transpac\u00edficas\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u2022 La reducci\u00f3n de calado en esclusas Neopanamax, junto con salidas en blanco y ajustes entre navieras, anticipa menor capacidad efectiva en corredores Asia\u2013Costa Este<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/restricciones-de-agosto-en-el-canal-de-panama-podrian-presionar-rutas-transpacificas\/\" aria-label=\"Read more about Restricciones de agosto en el Canal de Panam\u00e1 podr\u00edan presionar rutas transpac\u00edficas\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24344 post type-post status-publish format-standard has-post-thumbnail hentry category-best-practices-de-aduanas-y-puertos category-datos-curiosos category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/yangshan-y-singapur-lideran-rankings-portuarios-globales-bajo-metricas-distintas\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n3-1.png\" class=\"attachment-full size-full wp-image-24332\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n3-1.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n3-1-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n3-1-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/yangshan-y-singapur-lideran-rankings-portuarios-globales-bajo-metricas-distintas\/\" >\n\t\t\t\tYangshan y Singapur lideran rankings portuarios globales bajo m\u00e9tricas distintas\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u2022 El CPPI del Banco Mundial mide eficiencia operativa por tiempo de permanencia de buques, mientras el ranking de DNV y Menon Economics eval\u00faa competitividad<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/yangshan-y-singapur-lideran-rankings-portuarios-globales-bajo-metricas-distintas\/\" aria-label=\"Read more about Yangshan y Singapur lideran rankings portuarios globales bajo m\u00e9tricas distintas\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24338 post type-post status-publish format-standard has-post-thumbnail hentry category-global-customs-tech category-robots-en-la-cadena-logistica category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/ambi-robotics-y-pickle-robot-integran-solucion-robotica-para-automatizar-la-logistica-entrante\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n2-1.png\" class=\"attachment-full size-full wp-image-24331\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n2-1.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n2-1-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n2-1-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/ambi-robotics-y-pickle-robot-integran-solucion-robotica-para-automatizar-la-logistica-entrante\/\" >\n\t\t\t\tAmbi Robotics y Pickle Robot integran soluci\u00f3n rob\u00f3tica para automatizar la log\u00edstica entrante\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u2022 La alianza combina descarga automatizada de tr\u00e1ileres, escaneo, identificaci\u00f3n y paletizaci\u00f3n de paquetes en centros de distribuci\u00f3n. \u00a0 Ambi Robotics y Pickle Robot Company<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/14\/ambi-robotics-y-pickle-robot-integran-solucion-robotica-para-automatizar-la-logistica-entrante\/\" aria-label=\"Read more about Ambi Robotics y Pickle Robot integran soluci\u00f3n rob\u00f3tica para automatizar la log\u00edstica entrante\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24121 post type-post status-publish format-standard has-post-thumbnail hentry category-oportunidades-de-negocio category-tlc-news entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/13\/mexico-ampliara-sus-exportaciones-de-azucar-a-eeuu-tras-un-aumento-del-512-en-la-demanda\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n8.png\" class=\"attachment-full size-full wp-image-24122\" alt=\"\" srcset=\"https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n8.png 900w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n8-300x200.png 300w, https:\/\/tlcmagazinemexico.com.mx\/wp-content\/uploads\/2026\/07\/n8-768x512.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" style=\"width:100%;height:66.67%;max-width:900px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h1 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/13\/mexico-ampliara-sus-exportaciones-de-azucar-a-eeuu-tras-un-aumento-del-512-en-la-demanda\/\" >\n\t\t\t\tM\u00e9xico ampliar\u00e1 sus exportaciones de az\u00facar a EEUU tras un aumento del 512 % en la demanda\t\t\t<\/a>\n\t\t<\/h1>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>M\u00e9xico aumentar\u00e1 sus exportaciones de az\u00facar a Estados Unidos durante el pr\u00f3ximo ciclo comercial, luego de que el Departamento de Agricultura de Estados Unidos (USDA)<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/13\/mexico-ampliara-sus-exportaciones-de-azucar-a-eeuu-tras-un-aumento-del-512-en-la-demanda\/\" aria-label=\"Read more about M\u00e9xico ampliar\u00e1 sus exportaciones de az\u00facar a EEUU tras un aumento del 512 % en la demanda\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La econom\u00eda mexicana continu\u00f3 creciendo con equilibrios macroecon\u00f3micos s\u00f3lidos y, como ya se anticipaba, desde el Paquete Econ\u00f3mico, se prev\u00e9 que el PIB alcance el 3.0% en 2023. Esto ha sido posible gracias a las reformas implementadas por esta administraci\u00f3n, que han permitido alcanzar m\u00e1ximos hist\u00f3ricos en los niveles de empleo y en el poder&hellip; <a class=\"more-link\" href=\"https:\/\/tlcmagazinemexico.com.mx\/index.php\/2026\/07\/13\/mexico-ampliara-sus-exportaciones-de-azucar-a-eeuu-tras-un-aumento-del-512-en-la-demanda\/\">Seguir leyendo <span class=\"screen-reader-text\">M\u00e9xico ampliar\u00e1 sus exportaciones de az\u00facar a EEUU tras un aumento del 512 % en la demanda<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":3038,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tlc-news","entry"],"views":730,"_links":{"self":[{"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3386"}],"version-history":[{"count":5,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3386\/revisions"}],"predecessor-version":[{"id":3401,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3386\/revisions\/3401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3038"}],"wp:attachment":[{"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tlcmagazinemexico.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}